{"id":725,"date":"2026-05-10T12:00:07","date_gmt":"2026-05-10T08:30:07","guid":{"rendered":"https:\/\/noghresea.ir\/mag\/?p=725"},"modified":"2026-05-12T16:22:10","modified_gmt":"2026-05-12T12:52:10","slug":"silver-at-the-edge-of-uncertainty","status":"publish","type":"post","link":"https:\/\/noghresea.ir\/mag\/silver-at-the-edge-of-uncertainty\/","title":{"rendered":"\u0646\u0642\u0631\u0647 \u062f\u0631 \u0645\u0631\u0632 \u062a\u0631\u062f\u06cc\u062f\u061b \u0631\u0634\u062f\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u060c \u0633\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af"},"content":{"rendered":"<p data-start=\"292\" data-end=\"523\">\u062f\u0631 \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0631\u0648\u0632 \u062c\u0627\u0631\u06cc\u060c <a href=\"https:\/\/noghresea.ir\/ons\">\u0642\u06cc\u0645\u062a \u0627\u0648\u0646\u0633 \u0646\u0642\u0631\u0647<\/a> \u062f\u0631 \u0633\u0637\u062d <strong data-start=\"333\" data-end=\"349\">\u06f8\u06f0.\u06f3\u06f4\u06f7\u06f4 \u062f\u0644\u0627\u0631<\/strong> \u0645\u0639\u0627\u0645\u0644\u0647 \u0634\u062f\u061b \u0642\u06cc\u0645\u062a\u06cc \u06a9\u0647 \u0627\u06af\u0631\u0686\u0647 \u0646\u0633\u0628\u062a \u0628\u0647 \u0631\u0648\u0632 \u06af\u0630\u0634\u062a\u0647 <strong data-start=\"394\" data-end=\"416\">\u06f0.\u06f0\u06f0\u06f3\u06f9 \u062f\u0644\u0627\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634<\/strong> \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0631\u0634\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u062d\u062f\u0648\u062f\u060c \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0622\u0646\u06a9\u0647 \u0646\u0634\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u0642\u062f\u0631\u062a \u0628\u0627\u0634\u062f\u060c \u0628\u0627\u0632\u062a\u0627\u0628\u06cc \u0627\u0632 \u0627\u062d\u062a\u06cc\u0627\u0637 \u0628\u0627\u0632\u0627\u0631 \u0627\u0633\u062a.<\/p>\n<p data-start=\"525\" data-end=\"695\">\u0628\u0627\u0632\u0627\u0631\u06cc \u06a9\u0647 \u0627\u0645\u0631\u0648\u0632 \u0633\u0642\u0641 \u0642\u06cc\u0645\u062a\u06cc \u062e\u0648\u062f \u0631\u0627 \u0646\u06cc\u0632 \u062f\u0631 \u0647\u0645\u06cc\u0646 \u0645\u062d\u062f\u0648\u062f\u0647 \u062b\u0628\u062a \u06a9\u0631\u062f\u0647\u060c \u0639\u0645\u0644\u0627\u064b \u0641\u0627\u0642\u062f \u0645\u0648\u0645\u0646\u062a\u0648\u0645 \u0635\u0639\u0648\u062f\u06cc \u0642\u0648\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u06cc\u0639\u0646\u06cc \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631\u0627\u0646 \u0647\u0646\u0648\u0632 \u0628\u0631\u0627\u06cc \u0648\u0631\u0648\u062f \u062c\u062f\u06cc\u060c \u0628\u0647 \u0633\u06cc\u06af\u0646\u0627\u0644\u200c\u0647\u0627\u06cc \u0642\u0648\u06cc\u200c\u062a\u0631\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p data-start=\"525\" data-end=\"695\">\u062f\u0631 \u0646\u0642\u0631\u0647\u200c\u0633\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f <a href=\"https:\/\/noghresea.ir\/mag\/category\/silver-news\/\">\u0622\u062e\u0631\u06cc\u0646 \u0627\u062e\u0628\u0627\u0631 \u0646\u0642\u0631\u0647 \u0627\u0645\u0631\u0648\u0632<\/a> \u0631\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u0641\u0631\u0645\u0627\u06cc\u06cc\u062f.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/noghresea.ir\/mag\/silver-at-the-edge-of-uncertainty\/#%D8%A8%D8%A7%D8%B2%D8%AF%D9%87%DB%8C%E2%80%8C%D9%87%D8%A7_%DA%86%D9%87_%D9%85%DB%8C%E2%80%8C%DA%AF%D9%88%DB%8C%D9%86%D8%AF%D8%9F_%D9%86%D9%82%D8%B1%D9%87_%D8%AF%D8%B1_%DB%8C%DA%A9_%D8%B3%D8%A7%D9%84_%D8%AF%D8%B1%D8%AE%D8%B4%DB%8C%D8%AF\" >\u0628\u0627\u0632\u062f\u0647\u06cc\u200c\u0647\u0627 \u0686\u0647 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f\u061f \u0646\u0642\u0631\u0647 \u062f\u0631 \u06cc\u06a9 \u0633\u0627\u0644 \u062f\u0631\u062e\u0634\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/noghresea.ir\/mag\/silver-at-the-edge-of-uncertainty\/#%D8%B1%D9%82%D8%A7%D8%A8%D8%AA_%D9%81%D9%84%D8%B2%D8%A7%D8%AA_%DA%AF%D8%B1%D8%A7%D9%86%E2%80%8C%D8%A8%D9%87%D8%A7%D8%9B_%D9%86%D9%82%D8%B1%D9%87_%D8%AC%D8%A7_%D9%85%D8%A7%D9%86%D8%AF\" >\u0631\u0642\u0627\u0628\u062a \u0641\u0644\u0632\u0627\u062a \u06af\u0631\u0627\u0646\u200c\u0628\u0647\u0627\u061b \u0646\u0642\u0631\u0647 \u062c\u0627 \u0645\u0627\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/noghresea.ir\/mag\/silver-at-the-edge-of-uncertainty\/#%D8%AC%D8%AF%D9%88%D9%84_%D8%AA%D8%AD%D9%84%DB%8C%D9%84_%D8%AF%D8%A7%D8%AF%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D9%88%D9%86%D8%B3_%D9%86%D9%82%D8%B1%D9%87\" >\u062c\u062f\u0648\u0644 \u062a\u062d\u0644\u06cc\u0644 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0627\u0648\u0646\u0633 \u0646\u0642\u0631\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/noghresea.ir\/mag\/silver-at-the-edge-of-uncertainty\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C%D8%9B_%D9%86%D9%82%D8%B1%D9%87_%D8%AF%D8%B1_%D8%A2%D8%B3%D8%AA%D8%A7%D9%86%D9%87_%D8%AA%D8%B5%D9%85%DB%8C%D9%85\" >\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc\u061b \u0646\u0642\u0631\u0647 \u062f\u0631 \u0622\u0633\u062a\u0627\u0646\u0647 \u062a\u0635\u0645\u06cc\u0645<\/a><\/li><\/ul><\/nav><\/div>\n<h2 data-section-id=\"avu67t\" data-start=\"702\" data-end=\"771\"><span class=\"ez-toc-section\" id=\"%D8%A8%D8%A7%D8%B2%D8%AF%D9%87%DB%8C%E2%80%8C%D9%87%D8%A7_%DA%86%D9%87_%D9%85%DB%8C%E2%80%8C%DA%AF%D9%88%DB%8C%D9%86%D8%AF%D8%9F_%D9%86%D9%82%D8%B1%D9%87_%D8%AF%D8%B1_%DB%8C%DA%A9_%D8%B3%D8%A7%D9%84_%D8%AF%D8%B1%D8%AE%D8%B4%DB%8C%D8%AF\"><\/span>\u0628\u0627\u0632\u062f\u0647\u06cc\u200c\u0647\u0627 \u0686\u0647 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f\u061f \u0646\u0642\u0631\u0647 \u062f\u0631 \u06cc\u06a9 \u0633\u0627\u0644 \u062f\u0631\u062e\u0634\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p data-start=\"773\" data-end=\"848\">\u0646\u06af\u0627\u0647\u06cc \u0628\u0647 \u0628\u0627\u0632\u062f\u0647\u06cc\u200c\u0647\u0627\u06cc \u0632\u0645\u0627\u0646\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u062a\u0635\u0648\u06cc\u0631 \u0648\u0627\u0636\u062d\u200c\u062a\u0631\u06cc \u0627\u0632 \u0631\u0641\u062a\u0627\u0631 \u0646\u0642\u0631\u0647 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f:<\/p>\n<ul data-start=\"850\" data-end=\"1197\">\n<li data-section-id=\"ccus4s\" data-start=\"850\" data-end=\"950\">\u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 <strong data-start=\"861\" data-end=\"871\">\u0631\u0648\u0632\u0627\u0646\u0647<\/strong>\u060c \u0628\u0627\u0632\u062f\u0647\u06cc \u062d\u062f\u0648\u062f <strong data-start=\"885\" data-end=\"898\">\u06f0.\u06f6\u06f2 \u062f\u0631\u0635\u062f<\/strong> \u062b\u0628\u062a \u0634\u062f\u0647 \u06a9\u0647 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0645\u062d\u062f\u0648\u062f \u0648 \u06a9\u0645\u200c\u062c\u0627\u0646 \u0627\u0633\u062a.<\/li>\n<li data-section-id=\"b1wo94\" data-start=\"951\" data-end=\"1056\">\u062f\u0631 \u0628\u0627\u0632\u0647 <strong data-start=\"961\" data-end=\"972\">\u0633\u0647\u200c\u0645\u0627\u0647\u0647<\/strong>\u060c \u0646\u0642\u0631\u0647 \u0628\u0627 \u0627\u0641\u062a <strong data-start=\"986\" data-end=\"1000\">\u06f0.\u06f8\u06f4 \u062f\u0631\u0635\u062f\u06cc<\/strong> \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u0647\u061b \u0646\u0634\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u0635\u0644\u0627\u062d \u0642\u06cc\u0645\u062a\u06cc \u067e\u0633 \u0627\u0632 \u06cc\u06a9 \u062f\u0648\u0631\u0647 \u0631\u0634\u062f.<\/li>\n<li data-section-id=\"hpxqxh\" data-start=\"1057\" data-end=\"1197\">\u0627\u0645\u0627 \u062f\u0631 \u0646\u0645\u0627\u06cc <strong data-start=\"1071\" data-end=\"1081\">\u0633\u0627\u0644\u0627\u0646\u0647<\/strong>\u060c \u062f\u0627\u0633\u062a\u0627\u0646 \u06a9\u0627\u0645\u0644\u0627\u064b \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a\u061b \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0646\u0642\u0631\u0647 \u0628\u0627 \u0631\u0634\u062f \u062e\u06cc\u0631\u0647\u200c\u06a9\u0646\u0646\u062f\u0647 <strong data-start=\"1140\" data-end=\"1156\">\u06f1\u06f4\u06f6.\u06f3\u06f9 \u062f\u0631\u0635\u062f\u06cc<\/strong>\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u067e\u0631\u0628\u0627\u0632\u062f\u0647\u200c\u062a\u0631\u06cc\u0646 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/li>\n<\/ul>\n<p data-start=\"1199\" data-end=\"1316\">\u0627\u06cc\u0646 \u062a\u0636\u0627\u062f \u0645\u06cc\u0627\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f \u06a9\u0648\u062a\u0627\u0647\u200c\u0645\u062f\u062a \u0648 \u0628\u0644\u0646\u062f\u0645\u062f\u062a\u060c \u0647\u0645\u0627\u0646 \u0686\u06cc\u0632\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u062d\u0644\u06cc\u0644\u200c\u06af\u0631\u0627\u0646 \u0627\u0632 \u0622\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u00ab\u0641\u0627\u0632 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u0628\u0627\u0632\u0627\u0631\u00bb \u06cc\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<h2 data-section-id=\"3lmqez\" data-start=\"1323\" data-end=\"1360\"><span class=\"ez-toc-section\" id=\"%D8%B1%D9%82%D8%A7%D8%A8%D8%AA_%D9%81%D9%84%D8%B2%D8%A7%D8%AA_%DA%AF%D8%B1%D8%A7%D9%86%E2%80%8C%D8%A8%D9%87%D8%A7%D8%9B_%D9%86%D9%82%D8%B1%D9%87_%D8%AC%D8%A7_%D9%85%D8%A7%D9%86%D8%AF\"><\/span>\u0631\u0642\u0627\u0628\u062a \u0641\u0644\u0632\u0627\u062a \u06af\u0631\u0627\u0646\u200c\u0628\u0647\u0627\u061b \u0646\u0642\u0631\u0647 \u062c\u0627 \u0645\u0627\u0646\u062f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p data-start=\"1362\" data-end=\"1435\">\u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u060c \u0646\u0642\u0631\u0647 \u062f\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u0645\u062f\u062a \u0646\u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u0631\u0642\u0627\u0628\u062a \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u062f:<\/p>\n<ul data-start=\"1437\" data-end=\"1590\">\n<li data-section-id=\"1qautlh\" data-start=\"1437\" data-end=\"1515\">\u062f\u0631 \u06cc\u06a9 \u0645\u0627\u0647 \u0627\u062e\u06cc\u0631\u060c <strong data-start=\"1455\" data-end=\"1481\">\u0637\u0644\u0627 \u0628\u0627 \u0631\u0634\u062f \u06f1\u06f0.\u06f7\u06f6 \u062f\u0631\u0635\u062f\u06cc<\/strong> \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0647\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0646\u0642\u0631\u0647 \u062f\u0627\u0634\u062a\u0647<\/li>\n<li data-section-id=\"2fnjxp\" data-start=\"1516\" data-end=\"1590\">\u0647\u0645\u0686\u0646\u06cc\u0646 <strong data-start=\"1525\" data-end=\"1550\">\u0633\u06a9\u0647 \u0628\u0627 \u0631\u0634\u062f \u06f6.\u06f5\u06f9 \u062f\u0631\u0635\u062f\u06cc<\/strong> \u0627\u0632 \u0646\u0642\u0631\u0647 (<strong data-start=\"1560\" data-end=\"1572\">\u06f5.\u06f6 \u062f\u0631\u0635\u062f<\/strong>) \u067e\u06cc\u0634\u06cc \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a<\/li>\n<\/ul>\n<p data-start=\"1592\" data-end=\"1699\">\u0627\u06cc\u0646 \u06cc\u0639\u0646\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0641\u0639\u0644\u06cc\u060c \u062a\u0645\u0627\u06cc\u0644 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0647 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0627\u0645\u0646\u200c\u062a\u0631 \u06cc\u0627 \u0628\u0627 \u0645\u0648\u0645\u0646\u062a\u0648\u0645 \u0642\u0648\u06cc\u200c\u062a\u0631 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n<h2 data-section-id=\"126hvl5\" data-start=\"1706\" data-end=\"1738\"><span class=\"ez-toc-section\" id=\"%D8%AC%D8%AF%D9%88%D9%84_%D8%AA%D8%AD%D9%84%DB%8C%D9%84_%D8%AF%D8%A7%D8%AF%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D9%88%D9%86%D8%B3_%D9%86%D9%82%D8%B1%D9%87\"><\/span>\u062c\u062f\u0648\u0644 \u062a\u062d\u0644\u06cc\u0644 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0627\u0648\u0646\u0633 \u0646\u0642\u0631\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"TyagGW_tableContainer\">\n<div class=\"group TyagGW_tableWrapper flex flex-col-reverse w-fit\" tabindex=\"-1\">\n<div class=\"table-responsive-wrapper\"><table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"1740\" data-end=\"2384\">\n<thead data-start=\"1740\" data-end=\"1764\">\n<tr data-start=\"1740\" data-end=\"1764\">\n<th class=\"\" data-start=\"1740\" data-end=\"1747\" data-col-size=\"sm\">\u0634\u0627\u062e\u0635<\/th>\n<th class=\"\" data-start=\"1747\" data-end=\"1755\" data-col-size=\"sm\">\u0645\u0642\u062f\u0627\u0631<\/th>\n<th class=\"\" data-start=\"1755\" data-end=\"1764\" data-col-size=\"sm\">\u062a\u062d\u0644\u06cc\u0644<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"1792\" data-end=\"2384\">\n<tr data-start=\"1792\" data-end=\"1846\">\n<td data-start=\"1792\" data-end=\"1804\" data-col-size=\"sm\">\u0642\u06cc\u0645\u062a \u0641\u0639\u0644\u06cc<\/td>\n<td data-col-size=\"sm\" data-start=\"1804\" data-end=\"1819\">\u06f8\u06f0.\u06f3\u06f4\u06f7\u06f4 \u062f\u0644\u0627\u0631<\/td>\n<td data-col-size=\"sm\" data-start=\"1819\" data-end=\"1846\">\u062a\u062b\u0628\u06cc\u062a \u062f\u0631 \u0645\u062d\u062f\u0648\u062f\u0647 \u0645\u0642\u0627\u0648\u0645\u062a\u06cc<\/td>\n<\/tr>\n<tr data-start=\"1847\" data-end=\"1918\">\n<td data-start=\"1847\" data-end=\"1862\" data-col-size=\"sm\">\u062a\u063a\u06cc\u06cc\u0631 \u0631\u0648\u0632\u0627\u0646\u0647<\/td>\n<td data-col-size=\"sm\" data-start=\"1862\" data-end=\"1885\">+\u06f0.\u06f0\u06f0\u06f3\u06f9 \u062f\u0644\u0627\u0631 (\u06f0.\u06f6\u06f2\u066a)<\/td>\n<td data-col-size=\"sm\" data-start=\"1885\" data-end=\"1918\">\u0631\u0634\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u062d\u062f\u0648\u062f\u060c \u0646\u0634\u0627\u0646\u0647 \u0627\u062d\u062a\u06cc\u0627\u0637<\/td>\n<\/tr>\n<tr data-start=\"1919\" data-end=\"1972\">\n<td data-start=\"1919\" data-end=\"1932\" data-col-size=\"sm\">\u0642\u06cc\u0645\u062a \u062f\u06cc\u0631\u0648\u0632<\/td>\n<td data-col-size=\"sm\" data-start=\"1932\" data-end=\"1947\">\u06f8\u06f0.\u06f3\u06f4\u06f3\u06f5 \u062f\u0644\u0627\u0631<\/td>\n<td data-col-size=\"sm\" data-start=\"1947\" data-end=\"1972\">\u0627\u062e\u062a\u0644\u0627\u0641 \u0646\u0627\u0686\u06cc\u0632 \u0628\u0627 \u0627\u0645\u0631\u0648\u0632<\/td>\n<\/tr>\n<tr data-start=\"1973\" data-end=\"2033\">\n<td data-start=\"1973\" data-end=\"1994\" data-col-size=\"sm\">\u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0642\u06cc\u0645\u062a \u0627\u0645\u0631\u0648\u0632<\/td>\n<td data-col-size=\"sm\" data-start=\"1994\" data-end=\"2009\">\u06f8\u06f0.\u06f3\u06f4\u06f7\u06f4 \u062f\u0644\u0627\u0631<\/td>\n<td data-col-size=\"sm\" data-start=\"2009\" data-end=\"2033\">\u0646\u0628\u0648\u062f \u0646\u0648\u0633\u0627\u0646 \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647<\/td>\n<\/tr>\n<tr data-start=\"2034\" data-end=\"2093\">\n<td data-start=\"2034\" data-end=\"2050\" data-col-size=\"sm\">\u062a\u063a\u06cc\u06cc\u0631 \u0633\u0647\u200c\u0645\u0627\u0647\u0647<\/td>\n<td data-col-size=\"sm\" data-start=\"2050\" data-end=\"2074\">-\u06f0.\u06f8\u06f4\u066a (-\u06f0.\u06f6\u06f8\u06f5\u06f1 \u062f\u0644\u0627\u0631)<\/td>\n<td data-col-size=\"sm\" data-start=\"2074\" data-end=\"2093\">\u0627\u0635\u0644\u0627\u062d \u067e\u0633 \u0627\u0632 \u0631\u0634\u062f<\/td>\n<\/tr>\n<tr data-start=\"2094\" data-end=\"2157\">\n<td data-start=\"2094\" data-end=\"2109\" data-col-size=\"sm\">\u062a\u063a\u06cc\u06cc\u0631 \u0633\u0627\u0644\u0627\u0646\u0647<\/td>\n<td data-col-size=\"sm\" data-start=\"2109\" data-end=\"2134\">+\u06f1\u06f4\u06f6.\u06f3\u06f9\u066a (+\u06f4\u06f7.\u06f7\u06f3 \u062f\u0644\u0627\u0631)<\/td>\n<td data-col-size=\"sm\" data-start=\"2134\" data-end=\"2157\">\u0631\u0634\u062f \u0642\u062f\u0631\u062a\u0645\u0646\u062f \u0628\u0644\u0646\u062f\u0645\u062f\u062a<\/td>\n<\/tr>\n<tr data-start=\"2158\" data-end=\"2207\">\n<td data-start=\"2158\" data-end=\"2174\" data-col-size=\"sm\">\u0628\u0627\u0632\u062f\u0647\u06cc \u06f6 \u0645\u0627\u0647\u0647<\/td>\n<td data-col-size=\"sm\" data-start=\"2174\" data-end=\"2184\">+\u06f5\u06f8.\u06f9\u06f5\u066a<\/td>\n<td data-col-size=\"sm\" data-start=\"2184\" data-end=\"2207\">\u0631\u0648\u0646\u062f \u0635\u0639\u0648\u062f\u06cc \u0645\u06cc\u0627\u0646\u200c\u0645\u062f\u062a<\/td>\n<\/tr>\n<tr data-start=\"2208\" data-end=\"2257\">\n<td data-start=\"2208\" data-end=\"2224\" data-col-size=\"sm\">\u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u0627\u0647\u0627\u0646\u0647<\/td>\n<td data-col-size=\"sm\" data-start=\"2224\" data-end=\"2232\">+\u06f5.\u06f6\u066a<\/td>\n<td data-col-size=\"sm\" data-start=\"2232\" data-end=\"2257\">\u0631\u0634\u062f\u060c \u0627\u0645\u0627 \u06a9\u0645\u062a\u0631 \u0627\u0632 \u0631\u0642\u0628\u0627<\/td>\n<\/tr>\n<tr data-start=\"2258\" data-end=\"2321\">\n<td data-start=\"2258\" data-end=\"2283\" data-col-size=\"sm\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0637\u0644\u0627 (\u0645\u0627\u0647\u0627\u0646\u0647)<\/td>\n<td data-col-size=\"sm\" data-start=\"2283\" data-end=\"2298\">\u0646\u0642\u0631\u0647 \u0636\u0639\u06cc\u0641\u200c\u062a\u0631<\/td>\n<td data-col-size=\"sm\" data-start=\"2298\" data-end=\"2321\">\u0637\u0644\u0627 \u062c\u0644\u0648\u062a\u0631 \u0628\u0627 \u06f1\u06f0.\u06f7\u06f6\u066a<\/td>\n<\/tr>\n<tr data-start=\"2322\" data-end=\"2384\">\n<td data-start=\"2322\" data-end=\"2347\" data-col-size=\"sm\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0633\u06a9\u0647 (\u0645\u0627\u0647\u0627\u0646\u0647)<\/td>\n<td data-col-size=\"sm\" data-start=\"2347\" data-end=\"2362\">\u0646\u0642\u0631\u0647 \u0636\u0639\u06cc\u0641\u200c\u062a\u0631<\/td>\n<td data-col-size=\"sm\" data-start=\"2362\" data-end=\"2384\">\u0633\u06a9\u0647 \u062c\u0644\u0648\u062a\u0631 \u0628\u0627 \u06f6.\u06f5\u06f9\u066a<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/div>\n<\/div>\n<h2 data-section-id=\"1vus9vx\" data-start=\"2391\" data-end=\"2424\"><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C%D8%9B_%D9%86%D9%82%D8%B1%D9%87_%D8%AF%D8%B1_%D8%A2%D8%B3%D8%AA%D8%A7%D9%86%D9%87_%D8%AA%D8%B5%D9%85%DB%8C%D9%85\"><\/span>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc\u061b \u0646\u0642\u0631\u0647 \u062f\u0631 \u0622\u0633\u062a\u0627\u0646\u0647 \u062a\u0635\u0645\u06cc\u0645<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p data-start=\"2426\" data-end=\"2617\">\u0646\u0642\u0631\u0647 \u0627\u06a9\u0646\u0648\u0646 \u062f\u0631 \u0646\u0642\u0637\u0647\u200c\u0627\u06cc \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u06a9\u0647 \u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0622\u0646 \u0631\u0627 \u0635\u0639\u0648\u062f\u06cc \u062f\u0627\u0646\u0633\u062a \u0648 \u0646\u0647 \u0646\u0632\u0648\u0644\u06cc. \u0631\u0634\u062f\u0647\u0627\u06cc \u0645\u062d\u062f\u0648\u062f \u0631\u0648\u0632\u0627\u0646\u0647\u060c \u0627\u0641\u062a \u062e\u0641\u06cc\u0641 \u0633\u0647\u200c\u0645\u0627\u0647\u0647 \u0648 \u062f\u0631\u062e\u0634\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631 \u0633\u0627\u0644\u0627\u0646\u0647\u060c \u0647\u0645\u06af\u06cc \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u0628\u0627\u0632\u0627\u0631 \u062f\u0631 \u062d\u0627\u0644 \u00ab\u0647\u0636\u0645\u00bb \u06cc\u06a9 \u062c\u0647\u0634 \u0628\u0632\u0631\u06af \u0627\u0633\u062a.<\/p>\n<p data-start=\"2619\" data-end=\"2827\" data-is-last-node=\"\" data-is-only-node=\"\">\u0627\u06af\u0631 \u0633\u06cc\u06af\u0646\u0627\u0644\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0627\u0632 \u0633\u0645\u062a \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u06cc\u0627 \u062a\u0642\u0627\u0636\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0648\u0627\u0631\u062f \u0634\u0648\u062f\u060c \u0646\u0642\u0631\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0631 \u062f\u06cc\u06af\u0631 \u0634\u0639\u0644\u0647\u200c\u0648\u0631 \u0634\u0648\u062f. \u0627\u0645\u0627 \u062f\u0631 \u063a\u06cc\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a\u060c \u0627\u06cc\u0646 \u0641\u0644\u0632 \u0647\u0645\u0686\u0646\u0627\u0646 \u062f\u0631 \u0647\u0645\u06cc\u0646 \u0645\u062d\u062f\u0648\u062f\u0647\u200c\u0647\u0627\u06cc \u062e\u0627\u06a9\u0633\u062a\u0631\u06cc\u2014\u0645\u06cc\u0627\u0646 \u0627\u0645\u06cc\u062f \u0648 \u062a\u0631\u062f\u06cc\u062f\u2014\u0628\u0647 \u0646\u0648\u0633\u0627\u0646 \u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u062f.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;725&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;\u0627\u0645\u062a\u06cc\u0627\u0632 post&quot;,&quot;legend&quot;:&quot;0 \u0627\u0645\u062a\u06cc\u0627\u0632 \u0627\u0632 5&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;\u0646\u0642\u0631\u0647 \u062f\u0631 \u0645\u0631\u0632 \u062a\u0631\u062f\u06cc\u062f\u061b \u0631\u0634\u062f\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u060c \u0633\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score} \u0627\u0645\u062a\u06cc\u0627\u0632 \u0627\u0632 5&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            <span class=\"kksr-muted\">\u0627\u0645\u062a\u06cc\u0627\u0632 post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0642\u06cc\u0645\u062a \u0646\u0642\u0631\u0647 \u0627\u0645\u0631\u0648\u0632 \u0628\u0627 \u0631\u0634\u062f \u0645\u062d\u062f\u0648\u062f \u0628\u0647 \u06f8\u06f0.\u06f3\u06f4 \u062f\u0644\u0627\u0631 \u0631\u0633\u06cc\u062f\u061b \u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u062f\u0647\u06cc\u200c\u0647\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0646\u0642\u0631\u0647 \u062f\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u0645\u062f\u062a \u0636\u0639\u06cc\u0641 \u0627\u0645\u0627 \u062f\u0631 \u06cc\u06a9\u200c\u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u0628\u0633\u06cc\u0627\u0631 \u067e\u0631\u0628\u0627\u0632\u062f\u0647 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/p>\n","protected":false},"author":2,"featured_media":726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"noghresea_label":[],"class_list":["post-725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-silver-news"],"_links":{"self":[{"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/posts\/725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/comments?post=725"}],"version-history":[{"count":1,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/posts\/725\/revisions"}],"predecessor-version":[{"id":727,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/posts\/725\/revisions\/727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/media\/726"}],"wp:attachment":[{"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/media?parent=725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/categories?post=725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/tags?post=725"},{"taxonomy":"noghresea_label","embeddable":true,"href":"https:\/\/noghresea.ir\/mag\/wp-json\/wp\/v2\/noghresea_label?post=725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}